{"id":1159720,"date":"2020-05-06T00:00:00","date_gmt":"2020-05-05T17:00:00","guid":{"rendered":"https:\/\/pattayaprestigeproperties.com\/properties\/4-bed-4-bath-in-bang-saray-for-22900000-thb-pc7893\/"},"modified":"2024-08-16T16:26:25","modified_gmt":"2024-08-16T09:26:25","slug":"4-bed-4-bath-in-bang-saray-for-22900000-thb-pc7893","status":"publish","type":"property","link":"https:\/\/pattayaprestigeproperties.com\/fr\/properties\/4-bed-4-bath-in-bang-saray-for-22900000-thb-pc7893\/","title":{"rendered":"Baan Buraran Bang Saray &#8211; 4 Bed 4 Bath in Bang Saray for 22,900,000 THB PC7893"},"excerpt":{"rendered":"","protected":false},"author":22,"featured_media":1175990,"parent":0,"menu_order":0,"template":"","property_type":[8369],"property_status":[8303],"property_feature":[8288,8292,8289,10724,8331,8357],"property_label":[9223],"property_country":[8286],"property_city":[8285],"property_area":[8552],"class_list":["post-1159720","property","type-property","status-publish","has-post-thumbnail","hentry","property_prefix-pc-fr","property_type-house","property_status-out-of-market","property_feature-laundry","property_feature-air-conditioning","property_feature-parking","property_feature-pool-villa-fr","property_feature-golf-course-nearby","property_feature-storage-room","property_label-baan-buraran-bang-saray","property_country-thailand-fr","property_city-pattaya-fr","property_area-bang-saray"],"acf":[],"property_meta":{"_wp_page_template":["default"],"_icl_lang_duplicate_of":["374949"],"houzez_geolocation_lat":["12.748891657226219"],"houzez_geolocation_long":["100.90976912328402"],"_thumbnail_id":["1175990"],"houzez_total_property_views":["435"],"houzez_recently_viewed":["2026-07-16 01:47:57"],"houzez_manual_expire":["0"],"fave_property_size_prefix":["sqm"],"fave_property_land_postfix":["sqm"],"fave_private_note":["Update 09\/09\/22 Katy call &#013;\r\nThe owner say the house not for sale at the moment&#013;\r\n-------------------------------------------------&#013;\r\nListing from Khun Yui&#013;\r\nOwner want 20 Mb Net&#013;"],"fave_property_map":["1"],"fave_property_country":["Thailand"],"fave_agent_display_option":["agency_info"],"fave_prop_homeslider":["no"],"fave_floor_plans_enable":["disable"],"fave_additional_features_enable":["disable"],"fave_multiunit_plans_enable":["disable"],"fave_agents":["306803"],"fave_property_map_address":[""],"fave_property_location":["12.748891657226219,100.90976912328402"],"fave_property_electric_supply":["Yes"],"fave_description_en":["Baan Buraran, Thai Bali pool villa for Sale, is located in a private exclusive gated residential estate, in the Hills of Bangsaray surrounded by a natural green tropical forest and mountains. The estate sitting on a large 2400 sqm plot of land, composes of 2 buildings: the main house has a double story, with living room, western kitchen, 3 bedrooms, 2  bathrooms, with an amazing sea view from the second floor, and guest house has single-story 1 bedroom,  ensuite bathroom. The house enjoys opening patio to the outside verandas, big front gardens, and swimming pool, it comes fully furnished. The house is for sale in Thai name."],"fave_description_th":["\u0e1a\u0e49\u0e32\u0e19\u0e1a\u0e38\u0e23\u0e32\u0e23\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e44\u0e17\u0e22\u0e1a\u0e32\u0e2b\u0e25\u0e35\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e02\u0e15\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e31\u0e49\u0e27\u0e23\u0e2d\u0e1a\u0e02\u0e2d\u0e1a\u0e0a\u0e34\u0e14\u0e25\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e48\u0e32\u0e40\u0e02\u0e15\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e20\u0e39\u0e40\u0e02\u0e32 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48 2,400 \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e21\u0e15\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 2 \u0e2d\u0e32\u0e04\u0e32\u0e23: \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e35\u0e2a\u0e2d\u0e07\u0e0a\u0e31\u0e49\u0e19, \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19, \u0e04\u0e23\u0e31\u0e27\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01, 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19, 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33, \u0e27\u0e34\u0e27\u0e17\u0e30\u0e40\u0e25\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e17\u0e36\u0e48\u0e07\u0e08\u0e32\u0e01\u0e0a\u0e31\u0e49\u0e19\u0e2a\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e41\u0e02\u0e01 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e31\u0e49\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e21\u0e35 1 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19\u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e43\u0e19\u0e15\u0e31\u0e27 \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e2d\u0e2d\u0e01\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e07\u0e14\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e01\u0e2a\u0e27\u0e19\u0e14\u0e49\u0e32\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e02\u0e19\u0e32\u0e14\u0e43\u0e2b\u0e0d\u0e48\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e02\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e37\u0e48\u0e2d\u0e44\u0e17\u0e22"],"fave_description_fr":["Baan Buraran est situ\u00e9 dans un domaine r\u00e9sidentiel priv\u00e9 exclusif, dans les collines de Bangsaray, entour\u00e9 d'une for\u00eat tropicale verte naturelle et de montagnes. Le domaine sis sur un grand terrain de 2400 m\u00b2, est compos\u00e9 de 2 b\u00e2timents: la maison principale a un \u00e9tage, avec salon, cuisine occidentale, 3 chambres, 2 salles de bains, avec une vue imprenable sur la mer depuis le deuxi\u00e8me \u00e9tage, et une maison d'hote avec 1 chambre, salle de bains. La maison b\u00e9n\u00e9ficie d'un patio ouvrant sur les v\u00e9randas ext\u00e9rieures, de grands jardins \u00e0 l'avant et d'une piscine, elle est enti\u00e8rement meubl\u00e9e. La maison est \u00e0 vendre en nom tha\u00eflandais."],"fave_property_agency":["303074"],"_uag_page_assets":["a:9:{s:3:\"css\";s:32601:\".uagb-tabs__wrap{display:flex;margin:15px}.uagb-tabs__wrap ul.uagb-tabs__panel{margin:0;list-style-type:none;display:inherit}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-center{justify-content:center}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-left{justify-content:flex-start}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-right{justify-content:flex-end}.uagb-tabs__wrap ul.uagb-tabs__panel.uagb-tabs__align-right .uagb-tab:last-child{margin-right:0}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a{position:relative;padding:6px 12px;display:inline-flex}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-top{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-top .uagb-tabs__icon{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-bottom{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a.uagb-tabs__icon-position-bottom .uagb-tabs__icon{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel p{margin:0}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon{vertical-align:text-top}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-left{display:block;align-items:center}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-left .uagb-tabs__icon{display:flex;align-self:center}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-right{display:block}.uagb-tabs__wrap ul.uagb-tabs__panel .uagb-tabs__icon-position-right .uagb-tabs__icon{display:flex;align-self:center}.uagb-tabs__wrap .uagb-tabs__body-wrap{position:relative;max-width:100%;padding:10px}.editor-styles-wrapper .uagb-editor-preview-mode-tablet.uagb-tabs__wrap li.uagb-tab.uagb-tabs__add-tab,.editor-styles-wrapper .uagb-editor-preview-mode-mobile.uagb-tabs__wrap li.uagb-tab.uagb-tabs__add-tab{display:none}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop{flex-direction:column}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;align-items:center;flex-direction:row;max-width:100%;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-desktop .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-desktop .uagb-tabs__body-wrap{border:none}.uagb-tabs__wrap.uagb-tabs__hstyle3-desktop .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-desktop .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop ul.uagb-tabs__panel{justify-content:space-between;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop{flex-direction:row}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel{padding:0;display:flex;flex-direction:column;flex-grow:1;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{flex-grow:3}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle6-desktop .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-desktop .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop ul.uagb-tabs__panel{min-width:25%;max-width:25%}.uagb-tabs__wrap.uagb-tabs__vstyle8-desktop .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle9-desktop .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-desktop .uagb-tab{margin:10px 10px 10px 10px;text-align:center}@media (max-width: 1023px){.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet{flex-direction:column}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet ul.uagb-tabs__panel{margin-bottom:0;padding:0;max-width:100%;display:flex;flex-direction:row;flex-wrap:wrap}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-tablet .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-tablet .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle3-tablet .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-tablet .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet ul.uagb-tabs__panel{justify-content:flex-start;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-tablet .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet{flex-direction:row}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:column;flex-grow:1}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{flex-grow:3}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{max-width:75%}.uagb-tabs__wrap.uagb-tabs__vstyle6-tablet .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-tablet .uagb-tabs__body-wrap{border:none}.uagb-tabs__wrap.uagb-tabs__vstyle8-tablet ul.uagb-tabs__panel{margin-bottom:0;min-width:25%;max-width:25%;justify-content:normal}.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel{margin-bottom:0}.uagb-tabs__wrap.uagb-tabs__vstyle9-tablet ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle3-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle4-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle3-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__hstyle4-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle6-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle8-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle9-tablet,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle8-tablet .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-desktop.uagb-tabs__vstyle9-tablet .uagb-tabs__body-wrap{border-style:none}}@media (max-width: 767px){.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile{flex-direction:column;border-style:none}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:row;flex-grow:1;max-width:100%}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile .uagb-tabs__body-wrap{flex-direction:row;max-width:100%}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile{flex-direction:row;border-style:none}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel{margin-bottom:0;padding:0;display:flex;flex-direction:column;flex-grow:1}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile .uagb-tabs__body-wrap{flex-grow:3;max-width:75%}.uagb-tabs__wrap.uagb-tabs__hstyle1-mobile .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle2-mobile .uagb-tab{margin:10px 10px -1px 0}.uagb-tabs__wrap.uagb-tabs__hstyle3-mobile .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__hstyle4-mobile .uagb-tab{margin:10px 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile ul.uagb-tabs__panel{justify-content:flex-start;margin:0}.uagb-tabs__wrap.uagb-tabs__hstyle5-mobile .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle6-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle7-mobile ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 0 0}.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle8-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%}.uagb-tabs__wrap.uagb-tabs__vstyle9-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 10px 10px 0}.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel{min-width:24%;max-width:24%;margin:0}.uagb-tabs__wrap.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab{margin:10px 10px 10px 10px;text-align:center}.uagb-tabs__wrap.uagb-tabs__stack1-mobile,.uagb-tabs__wrap.uagb-tabs__stack2-mobile,.uagb-tabs__wrap.uagb-tabs__stack3-mobile,.uagb-tabs__wrap.uagb-tabs__stack4-mobile{display:block}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel{margin:0;padding:0;display:flex;flex-direction:column;max-width:100%;flex-grow:unset}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab{width:100%}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab p,.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack2-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack3-mobile .uagb-tabs__body-wrap,.uagb-tabs__wrap.uagb-tabs__stack4-mobile .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__stack1-mobile{display:block}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel{margin:0;padding:0;display:flex;flex-direction:column;max-width:100%;flex-grow:unset}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile ul.uagb-tabs__panel .uagb-tab p{margin:0}.uagb-tabs__wrap.uagb-tabs__stack1-mobile .uagb-tabs__body-wrap{max-width:100%}.uagb-tabs__wrap.uagb-tabs__stack2-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0}.uagb-tabs__wrap.uagb-tabs__stack3-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0;padding:6px 12px 6px 12px}.uagb-tabs__wrap.uagb-tabs__stack4-mobile{margin:auto}.uagb-tabs__wrap.uagb-tabs__stack4-mobile ul.uagb-tabs__panel .uagb-tab{margin:0 0 10px 0;text-align:center}}.uagb-tabs__wrap .uagb-tabs__body-container.uagb-tabs-body__active{display:block}\n.uagb-tabs__wrap .uagb-tabs__body-container{padding:10px 15px;display:none}\n.uagb-block-364ad84b .uagb-tabs__panel .uagb-tab {background: #bd8e39;text-align: left;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab a {color: #1c1e4b;}.uagb-block-364ad84b .uagb-tabs__panel .uagb-tab.uagb-tabs__active{background: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__wrap ul.uagb-tabs__panel li.uagb-tab.uagb-tabs__active a{color: #ffffff;}.uagb-block-364ad84b .uagb-tabs__body-wrap p {color: #1c1e4b;}.uagb-block-364ad84b .uagb-tabs__icon svg{height: 16px;width: 16px;}.uagb-block-364ad84b .uagb-tabs__icon-position-left > .uagb-tabs__icon{margin-right: 10px;}.uagb-block-364ad84b .uagb-tabs__icon-position-right > .uagb-tabs__icon{margin-left: 10px;}.uagb-block-364ad84b .uagb-tabs__icon-position-bottom > .uagb-tabs__icon{margin-top: 10px;}.uagb-block-364ad84b .uagb-tabs__icon-position-top > .uagb-tabs__icon{margin-bottom: 10px;}.uagb-block-364ad84b.uagb-tabs__hstyle1-desktop > .uagb-tabs__panel .uagb-tab{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle1-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle2-desktop > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle2-desktop ul.uagb-tabs__panel{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle2-desktop > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle3-desktop .uagb-tab{border-bottom-width: 1px;border-bottom: 0;outline: 0;border-radius: 0;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle3-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle4-desktop .uagb-tab{border-radius: 30px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle4-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle5-desktop{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__hstyle5-desktop .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-364ad84b.uagb-tabs__hstyle5-desktop .uagb-tab.uagb-tabs__active{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle6-desktop .uagb-tab{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle6-desktop .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle7-desktop .uagb-tab{border-top-width: 1px;border-right-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle7-desktop > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle8-desktop .uagb-tab{border-right-width: 1px;border-right: 0;outline: 0;border-radius: 0;border-top-width: 1px;border-left-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle8-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle9-desktop .uagb-tab{border-radius: 30px;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle9-desktop > .uagb-tabs__body-wrap{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle10-desktop{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-desktop .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-desktop ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top-width: 1px;border-bottom-width: 1px;border-left-width: 1px;border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-right-width: 1px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #bd8e39;border-style: solid;}.uagb-block-364ad84b ul.uagb-tabs__panel{margin-right: auto;margin-left: 0;}.uagb-block-364ad84b  .uagb-tabs__panel .uagb-tab a{font-weight: 500;}@media only screen and (max-width: 976px) {.uagb-block-364ad84b.uagb-tabs__hstyle1-tablet > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle1-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle2-tablet > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle2-tablet ul.uagb-tabs__panel{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle2-tablet > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle3-tablet .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle3-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle4-tablet .uagb-tab{border-radius: 30px;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle4-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle5-tablet{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle5-tablet .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-364ad84b.uagb-tabs__hstyle5-tablet .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle6-tablet .uagb-tab{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle6-tablet .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle7-tablet .uagb-tab{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle7-tablet > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle8-tablet .uagb-tab{border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle8-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle9-tablet .uagb-tab{border-radius: 30px;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle9-tablet > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle10-tablet{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-tablet .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-tablet ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}}@media only screen and (max-width: 767px) {.uagb-block-364ad84b.uagb-tabs__hstyle1-mobile > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle1-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle2-mobile > .uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle2-mobile ul.uagb-tabs__panel{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle2-mobile > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__hstyle3-mobile .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle3-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle4-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle4-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle5-mobile{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__hstyle5-mobile .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-364ad84b.uagb-tabs__hstyle5-mobile .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle6-mobile .uagb-tab{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle6-mobile .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle7-mobile .uagb-tab{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle7-mobile > .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle8-mobile .uagb-tab{border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle8-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle9-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle9-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle10-mobile{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-mobile .uagb-tabs__body-wrap{border-width: 0px;border-style: none;}.uagb-block-364ad84b.uagb-tabs__vstyle10-mobile ul.uagb-tabs__panel .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack11-mobile > .uagb-tabs__panel .uagb-tab{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack11-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack12-mobile .uagb-tab{border-bottom: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack12-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack13-mobile .uagb-tab{border-radius: 30px;border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack13-mobile > .uagb-tabs__body-wrap{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack14-mobile{border-style: solid;border-color: #bd8e39;}.uagb-block-364ad84b.uagb-tabs__stack14-mobile .uagb-tab{border-top-width: 0px;border-right-width: 0px;border-left-width: 0px;border-bottom-width: 0px;border-top: 0;border-left: 0;border-right: 0;border-bottom: 0;outline: 0;border-radius: 0;}.uagb-block-364ad84b.uagb-tabs__stack14-mobile .uagb-tab.uagb-tabs__active{border-top: 0;border-left: 0;border-right: 0;outline: 0;border-radius: 0;border-style: solid;border-color: #bd8e39;}}\";s:2:\"js\";s:315:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBTabs.init( '.uagb-block-364ad84b' );\n\tUAGBTabs.anchorTabId( '.uagb-block-364ad84b' );\n});\nwindow.addEventListener( 'hashchange', function() {\n\tUAGBTabs.anchorTabId( '.uagb-block-364ad84b' );\n}, false );\n })\";s:18:\"current_block_list\";a:5:{i:0;s:9:\"uagb\/tabs\";i:1;s:15:\"uagb\/tabs-child\";i:2;s:14:\"core\/paragraph\";i:3;s:14:\"core\/separator\";i:4;s:11:\"core\/spacer\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1674964319\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"_uag_css_file_name":["uag-css-374949-1675234609.css"],"_uag_js_file_name":["uag-js-374949-1675234609.js"],"fave_revision_log":[" new bedroom "],"fave_property_size":["700"],"fave_property_land":["2400"],"fave_property_kitchen_type":["European"],"fave_property_garage":["Yes"],"fave_property_balcony":["Yes"],"fave_staff-bedrooms":["1"],"fave_staff-bathrooms":["1"],"fave_aircon":["Full"],"fave_property_security":["24 Hour"],"fave_furniture":["Fully"],"fave_property_garden":["Private"],"fave_property_swimmingpool":["Private"],"fave_end_rental":["1588291200"],"fave_sale_commission_rental":["5"],"fave_rent_lease_period_month":["N\/A"],"fave_rent_commission":["N\/A"],"fave_deposit":["0"],"fave_transfer_frees":["3"],"fave_negotiable":["1"],"fave_key_money":["0"],"fave_key_money_amout":["0"],"fave_currently_operating":["0"],"fave_featured":["0"],"fave_property_street_number":["218\/1, moo 6, Sattah"],"fave_property_address":["Bangsaray"],"fave_property_zip":["20250"],"fave_property_id":["PC7893"],"fave_property_bedrooms":["4"],"fave_property_bathrooms":["4"],"fave_property_price":["22900000"],"houzez_views_by_date":["a:61:{s:10:\"02-03-2026\";i:1;s:10:\"02-06-2026\";i:1;s:10:\"02-07-2026\";i:1;s:10:\"02-08-2026\";i:1;s:10:\"02-09-2026\";i:1;s:10:\"02-10-2026\";i:2;s:10:\"02-12-2026\";i:1;s:10:\"02-13-2026\";i:1;s:10:\"02-15-2026\";i:1;s:10:\"02-19-2026\";i:1;s:10:\"02-21-2026\";i:1;s:10:\"02-22-2026\";i:1;s:10:\"02-25-2026\";i:1;s:10:\"02-27-2026\";i:1;s:10:\"03-01-2026\";i:1;s:10:\"03-06-2026\";i:1;s:10:\"03-07-2026\";i:1;s:10:\"03-10-2026\";i:1;s:10:\"03-12-2026\";i:1;s:10:\"03-13-2026\";i:1;s:10:\"03-14-2026\";i:1;s:10:\"03-19-2026\";i:2;s:10:\"03-25-2026\";i:1;s:10:\"03-26-2026\";i:1;s:10:\"03-28-2026\";i:1;s:10:\"03-30-2026\";i:1;s:10:\"04-02-2026\";i:1;s:10:\"04-03-2026\";i:1;s:10:\"04-08-2026\";i:1;s:10:\"04-10-2026\";i:1;s:10:\"04-12-2026\";i:2;s:10:\"04-13-2026\";i:1;s:10:\"04-15-2026\";i:2;s:10:\"04-18-2026\";i:1;s:10:\"04-25-2026\";i:1;s:10:\"04-26-2026\";i:1;s:10:\"04-29-2026\";i:1;s:10:\"04-30-2026\";i:1;s:10:\"05-05-2026\";i:1;s:10:\"05-07-2026\";i:1;s:10:\"05-08-2026\";i:1;s:10:\"05-11-2026\";i:4;s:10:\"05-13-2026\";i:1;s:10:\"05-15-2026\";i:1;s:10:\"05-16-2026\";i:1;s:10:\"05-18-2026\";i:2;s:10:\"05-19-2026\";i:3;s:10:\"05-26-2026\";i:2;s:10:\"06-02-2026\";i:1;s:10:\"06-03-2026\";i:1;s:10:\"06-04-2026\";i:2;s:10:\"06-08-2026\";i:1;s:10:\"06-14-2026\";i:2;s:10:\"06-15-2026\";i:2;s:10:\"06-23-2026\";i:1;s:10:\"06-25-2026\";i:1;s:10:\"06-28-2026\";i:1;s:10:\"07-07-2026\";i:1;s:10:\"07-12-2026\";i:2;s:10:\"07-14-2026\";i:1;s:10:\"07-15-2026\";i:2;}"],"customer_first_name":["Jim"],"customer_second_name":["Fisher"],"customer_email":["jim.fisher1914@gmail.com"],"customer_phone":["085-845-6963"],"customer_country":["Thailand"],"ref_country":["Thailand"],"fave_property_lat_long":["12.748891657226219,100.90976912328402"],"fave_seller_display_option":["existing_seller"],"fave_ownership":["Thai"],"fave_property_customer":["605399"],"_wds_readability":["a:4:{s:5:\"score\";i:0;s:9:\"raw_score\";b:0;s:11:\"is_readable\";b:0;s:5:\"error\";s:19:\"No content to check\";}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["0"],"_wpml_word_count":["{\"total\":28,\"to_translate\":{\"fr\":28,\"th\":28}}"],"fave_publish_down":["0"],"fave_property_sub_divided":["No"],"fave_property_map_street_view":["hide"],"fave_property_images":["1175989","1175932","1175935","1175938","1175941","1175944","1175947","1175950","1175953","1175956","1175959","1175962","1175965","1175968","1175971","1175974","1175977","1175980","1175983","1175986","1175992","1175995","1175998","1176001","1176004","1176007","1176010"],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"my_revision_logs":["Revision Logs"],"customer_mobile":[""],"customer_fax":[""],"customer_street":[""],"customer_location":[""],"customer_state":[""],"customer_postal_code":[""],"customer_ref_remark":[""],"ref_first_name":[""],"ref_second_name":[""],"ref_email":[""],"ref_phone":[""],"ref_mobile":[""],"ref_fax":[""],"ref_street":[""],"ref_location":[""],"ref_state":[""],"ref_postal_code":[""],"ref_remark":[""],"_houzez_expiration_date_status":["saved"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties\/1159720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/users\/22"}],"version-history":[{"count":0,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties\/1159720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/media\/1175990"}],"wp:attachment":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/media?parent=1159720"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_type?post=1159720"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_status?post=1159720"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_feature?post=1159720"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_label?post=1159720"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_country?post=1159720"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_city?post=1159720"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_area?post=1159720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}