{"id":1294066,"date":"2023-08-29T17:20:21","date_gmt":"2023-08-29T10:20:21","guid":{"rendered":"https:\/\/pattayaprestigeproperties.com\/?post_type=property&#038;p=1294066"},"modified":"2026-03-30T10:29:42","modified_gmt":"2026-03-30T03:29:42","slug":"silk-road-3-bed-2-bath-in-east-pattaya-pp9788","status":"publish","type":"property","link":"https:\/\/pattayaprestigeproperties.com\/fr\/properties\/silk-road-3-bed-2-bath-in-east-pattaya-pp9788\/","title":{"rendered":"Silk Road &#8211; 3 bed 2 bath in East Pattaya PP9788"},"excerpt":{"rendered":"","protected":false},"author":32,"featured_media":1294094,"parent":0,"menu_order":0,"template":"","property_type":[8369],"property_status":[8302],"property_feature":[4146,5904,4000,3998,3999,10718],"property_label":[7404],"property_country":[67],"property_city":[8285],"property_area":[3933],"class_list":["post-1294066","property","type-property","status-publish","has-post-thumbnail","hentry","property_prefix-pc","xml-exclude","property_type-house","property_status-for-sale-or-rent","property_feature-air-conditioning","property_feature-close-to-the-beach","property_feature-fitness-center","property_feature-golf-course-nearby","property_feature-parking","property_feature-pool-villa","property_label-silk-road-place","property_country-thailand","property_city-pattaya-fr","property_area-east-pattaya"],"acf":[],"property_meta":{"_wds_readability":["a:4:{s:5:\"score\";i:0;s:9:\"raw_score\";b:0;s:11:\"is_readable\";b:0;s:5:\"error\";s:19:\"No content to check\";}"],"_wpml_word_count":["6"],"_edit_lock":["1774841353:18"],"_edit_last":["18"],"my_revision_logs":["Revision Logs\r\n-----------------------\r\nKik Raweewan made the following changes on 13:39 at  -- 29-08-2023 -- \r\n-- changed property status from Select Status to For Sale\r\n-----------------------\r\nKik Raweewan made the following changes on 13:47 at  -- 29-08-2023 -- \r\n-- changed property location from Select Location to East Pattaya\r\n-----------------------\r\nKik Raweewan made the following changes on 13:47 at  -- 29-08-2023 -- \r\n-- added 13500000 to sale price\r\n-----------------------\r\nKik Raweewan made the following changes on 13:48 at  -- 29-08-2023 -- \r\n-- changed development from Select a development to Silk Road\r\n-----------------------\r\nKik Raweewan made the following changes on 14:04 at  -- 29-08-2023 -- \r\n-- added 452 to land area\r\n-----------------------\r\nKik Raweewan made the following changes on 14:09 at  -- 29-08-2023 -- \r\n-- added 29-8-2023 to Available Date\r\n-----------------------\r\nKik Raweewan made the following changes on 14:09 at  -- 29-08-2023 -- \r\n-- added 5 to Sale Commision Rental\r\n-----------------------\r\nKik Raweewan made the following changes on 14:09 at  -- 29-08-2023 -- \r\n-- changed Transfer Fees from N\/A to 50\/50\r\n-----------------------\r\nKik Raweewan made the following changes on 14:11 at  -- 29-08-2023 -- \r\n-- added https:\/\/goo.gl\/maps\/C7q8GoSbqg3pYj1LA to Link For Real Lat & Long\r\n-----------------------\r\nKik Raweewan made the following changes on 14:11 at  -- 29-08-2023 -- \r\n-- added 12.88064815910116, 100.91689445215344 to Lat & Long\r\nKik Raweewan made the following changes on  -- 29-08-2023 --  at 14:13\r\n-- edited private notes\r\nKik Raweewan made the following changes on  -- 29-08-2023 --  at 14:15\r\n-- edited private notes\r\nKik Raweewan made the following changes on  -- 29-08-2023 --  at 14:18\r\n-- edited private notes\r\nKik Raweewanmade the following changes on  -- 29-08-2023 --  at 14:24\r\n-- Added Image\r\nKik Raweewanmade the following changes on  -- 29-08-2023 --  at 14:27\r\n-- Added Image\r\n-----------------------\r\nKik Raweewan made the following changes on 15:12 at  -- 29-08-2023 -- \r\n-- added \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n to description_en\r\n-----------------------\r\nKik Raweewan made the following changes on 15:12 at  -- 29-08-2023 -- \r\n-- added \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n to description_th\r\n-----------------------\r\nKik Raweewan made the following changes on 15:13 at  -- 29-08-2023 -- \r\n-- changed description_en from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n to \r\n\r\n-----------------------\r\nKik Raweewan made the following changes on 15:13 at  -- 29-08-2023 -- \r\n-- changed description_en from \r\n to Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\n-----------------------\r\nKik Raweewan made the following changes on 15:13 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 480 \u0e15\u0e23.\u0e21.(120 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\r\n-----------------------\r\nKik Raweewan made the following changes on 15:13 at  -- 29-08-2023 -- \r\n-- changed description_en from Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n to Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms.\r\n-----------------------\r\nKik Raweewan made the following changes on 15:14 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 480 \u0e15\u0e23.\u0e21.(120 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33\r\n-----------------------\r\nKik Raweewan made the following changes on 15:16 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n \u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \r\n-----------------------\r\nKik Raweewan made the following changes on 15:17 at  -- 29-08-2023 -- \r\n-- changed description_en from Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. to Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience.\r\n-----------------------\r\nKik Raweewan made the following changes on 15:18 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33  to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\r\n\r\n-----------------------\r\nKik Raweewan made the following changes on 15:19 at  -- 29-08-2023 -- \r\n-- changed description_en from Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience. to Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience.\r\n\r\nThis house is\r\n-----------------------\r\nKik Raweewan made the following changes on 15:19 at  -- 29-08-2023 -- \r\n-- changed description_en from Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience.\r\n\r\nThis house is to Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience.\r\n\r\nThis house is for sale in Thai name.\r\n-----------------------\r\nKik Raweewan made the following changes on 15:20 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\r\n to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e02\u0e32\u0e22\u0e43\u0e19\u0e01\u0e23\r\n\r\n\r\n\r\n-----------------------\r\nKik Raweewan made the following changes on 15:21 at  -- 29-08-2023 -- \r\n-- changed description_th from \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e02\u0e32\u0e22\u0e43\u0e19\u0e01\u0e23\r\n\r\n\r\n to \u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e02\u0e32\u0e22\u0e43\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e44\u0e17\u0e22\r\n\r\n\r\n\r\n-----------------------\r\nKik Raweewan made the following changes on 15:21 at  -- 29-08-2023 -- \r\n-- added Silk Road Place, un d\u00e9veloppement r\u00e9sidentiel exquis et luxueux, est situ\u00e9 dans le soi Chaiyapruk 2, id\u00e9alement \u00e0 proximit\u00e9 des commerces et des services, tout en offrant \u00e9galement un acc\u00e8s facile aux plages de Pattaya et de Jomtien en quelques minutes en voiture. Il a acquis une r\u00e9putation louable gr\u00e2ce \u00e0 son excellent entretien et \u00e0 son haut niveau de s\u00e9curit\u00e9. De plus, les r\u00e9sidents peuvent profiter des fantastiques installations communes, qui comprennent une piscine commune rafra\u00eechissante, une salle de sport bien \u00e9quip\u00e9e, une charmante aire de jeux pour enfants et de magnifiques jardins communaux paysagers.\r\n\r\nCette maison, assise sur un terrain de 452 m2, se compose de 3 chambres, 2 salles de bains. La maison est en partie meubl\u00e9e et pr\u00e9sente une cuisine moderne, une salle \u00e0 manger accueillante, un salon spacieux et un parking couvert pour votre commodit\u00e9.\r\n\r\nCette maison est \u00e0 vendre au nom tha\u00eflandais. to description_fr\r\n-----------------------\r\nKik Raweewan made the following changes on 15:22 at  -- 29-08-2023 -- \r\n-- removed Silk Road Place, un d\u00e9veloppement r\u00e9sidentiel exquis et luxueux, est situ\u00e9 dans le soi Chaiyapruk 2, id\u00e9alement \u00e0 proximit\u00e9 des commerces et des services, tout en offrant \u00e9galement un acc\u00e8s facile aux plages de Pattaya et de Jomtien en quelques minutes en voiture. Il a acquis une r\u00e9putation louable gr\u00e2ce \u00e0 son excellent entretien et \u00e0 son haut niveau de s\u00e9curit\u00e9. De plus, les r\u00e9sidents peuvent profiter des fantastiques installations communes, qui comprennent une piscine commune rafra\u00eechissante, une salle de sport bien \u00e9quip\u00e9e, une charmante aire de jeux pour enfants et de magnifiques jardins communaux paysagers.\r\n\r\nCette maison, assise sur un terrain de 452 m2, se compose de 3 chambres, 2 salles de bains. La maison est en partie meubl\u00e9e et pr\u00e9sente une cuisine moderne, une salle \u00e0 manger accueillante, un salon spacieux et un parking couvert pour votre commodit\u00e9.\r\n\r\nCette maison est \u00e0 vendre au nom tha\u00eflandais. from description_fr\r\n-----------------------\r\nKik Raweewan made the following changes on 15:22 at  -- 29-08-2023 -- \r\n-- added Silk Road Place, un d\u00e9veloppement r\u00e9sidentiel exquis et luxueux, est situ\u00e9 dans le soi Chaiyapruk 2, id\u00e9alement \u00e0 proximit\u00e9 des commerces et des services, tout en offrant \u00e9galement un acc\u00e8s facile aux plages de Pattaya et de Jomtien en quelques minutes en voiture. Il a acquis une r\u00e9putation louable gr\u00e2ce \u00e0 son excellent entretien et \u00e0 son haut niveau de s\u00e9curit\u00e9. De plus, les r\u00e9sidents peuvent profiter des fantastiques installations communes, qui comprennent une piscine commune rafra\u00eechissante, une salle de sport bien \u00e9quip\u00e9e, une charmante aire de jeux pour enfants et de magnifiques jardins communaux paysagers.\r\n\r\nCette maison, assise sur un terrain de 452 m2, se compose de 3 chambres, 2 salles de bains. La maison est en partie meubl\u00e9e et pr\u00e9sente une cuisine moderne, une salle \u00e0 manger accueillante, un salon spacieux et un parking couvert pour votre commodit\u00e9.\r\n\r\nCette maison est \u00e0 vendre au nom tha\u00eflandais to description_fr\r\nKhiat Phimsawan made the following changes on  -- 19-07-2024 --  at 16:06\r\n-- edited private notes\r\n-----------------------\r\nKhiat Phimsawan made the following changes on 16:06 at  -- 19-07-2024 -- \r\n-- changed property status from For Sale to Rented & For Sale\r\n-----------------------\r\nKhiat Phimsawan made the following changes on 16:06 at  -- 19-07-2024 -- \r\n-- changed Available Date from 29-8-2023 to 29-2-2025\r\n-----------------------\r\nKhiat Phimsawan made the following changes on 16:06 at  -- 19-07-2024 -- \r\n-- changed Available Date from 29-2-2025 to 28-2-2025\r\n-----------------------\r\nKhiat Phimsawan made the following changes on 16:37 at  -- 19-07-2024 -- \r\n-- changed sale price from 13500000 to 14500000\r\n-----------------------\r\nFrank Akkhawat made the following changes on  -- 30-04-2025 --  at 11:58\r\n-- edited private notes\r\n-----------------------\r\nFrank Akkhawat made the following changes on 12:08 at  -- 30-04-2025 -- \r\n-- changed property status from For Sale Or Rent to Rented & For Sale\r\n-----------------------\r\nFrank Akkhawat made the following changes on 12:08 at  -- 30-04-2025 -- \r\n-- changed Available Date from 28-2-2025 to 30-6-2025\r\n-----------------------\r\nFrank Akkhawat made the following changes on 12:08 at  -- 30-04-2025 -- \r\n-- added 65000 to rent price\r\n-----------------------\r\nFoei Pacharin made the following changes on 09:54 at  -- 04-12-2025 -- \r\n-- changed Available Date from 30-6-2025 to 31-3-2026\r\n-----------------------\r\nFoei Pacharin made the following changes on 09:54 at  -- 04-12-2025 -- \r\n-- changed property status from For Sale Or Rent to Rented & For Sale\r\n-----------------------\r\nFoei Pacharin made the following changes on  -- 04-12-2025 --  at 09:55\r\n-- edited private notes\r\n-----------------------\r\nYui Jeerat made the following changes on 10:29 at  -- 30-03-2026 -- \r\n-- changed Available Date from 31-3-2026 to 30-6-2026\r\n-----------------------"],"fave_publish_down":["0"],"fave_property_price":["14500000"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_property_land":["452"],"fave_property_land_postfix":["sqm"],"fave_property_kitchen_type":["N\/A"],"fave_property_garage":["Yes"],"fave_property_electric_supply":["Yes"],"fave_property_water":["Yes"],"fave_property_sub_divided":["No"],"fave_aircon":["Full"],"fave_property_security":["24 Hour"],"fave_furniture":["Fully"],"fave_property_garden":["Private"],"fave_property_swimmingpool":["Private"],"fave_ownership":["Thai"],"fave_property_map":["1"],"fave_property_location":["12.88064815910116, 100.91689445215344"],"houzez_geolocation_lat":["12.88064815910116"],"houzez_geolocation_long":[" 100.91689445215344"],"fave_property_lat_long":["12.88064815910116, 100.91689445215344"],"fave_property_map_street_view":["hide"],"fave_property_lat_long_link":["https:\/\/goo.gl\/maps\/C7q8GoSbqg3pYj1LA"],"fave_property_street_number":["House No.99\/1"],"fave_property_address":["Chaiyapruk 2"],"fave_property_zip":["20150"],"fave_featured":["0"],"fave_exclusive":["0"],"fave_loggedintoview":["0"],"fave_agent_display_option":["agency_info"],"fave_property_agency":["303074"],"fave_seller_display_option":["existing_seller"],"fave_private_note":["4\/12\/25 available for sale, rented till April 2026\/ Pui call\r\nWill be available to rent 65k end of June 2025. Frank call 30\/4\/25\r\n----------------------\r\nCalled, rented until end of Feb. 2025 @65,000\/month, Sales price increased from 13.5mill to 14.5mill, including 5% commission, for sale with sit-in tenant .... Khiat 19\/7\/2024\r\n.........\r\n-The Owner is her boss . she is secretary\r\n- Listing from K.Toon.\r\n-Wait until the tenant moves out by the end of 2023, then sell.\r\n- maintenance  54,000\/year."],"fave_single_top_area":["global"],"fave_single_content_area":["global"],"fave_end_rental":["1782777600"],"fave_sale_commission_rental":["5"],"fave_rent_lease_period_month":["N\/A"],"fave_rent_commission":["N\/A"],"fave_transfer_frees":["3"],"fave_negotiable":["0"],"fave_key_money":["0"],"fave_currently_operating":["0"],"fave_property_id":["PP9788"],"fave_property_customer":["1294105"],"customer_first_name":["Naporn"],"customer_second_name":["Pechdong"],"customer_phone":["095-962-2189"],"houzez_manual_expire":["0"],"_houzez_expiration_date_status":["saved"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["1294094"],"fave_description_en":["Silk Road Place, an exquisite and luxurious residential development, is located in soi Chaiyapruk 2, conveniently close to shops and services, while also offering easy access to both Pattaya and Jomtien beaches with just a short drive. It has earned a commendable reputation for its excellent maintenance and high-level security. Moreover, residents can enjoy the fantastic communal facilities, which include a refreshing communal pool, well-equipped gym, a delightful children's playground, and beautifully landscaped communal gardens. \r\n\r\nThis house sitting on a 452 sqm plot of land, consists of 3 bedrooms, 2 bathrooms. The house is partly furnished, showcasing a modern kitchen, an inviting dining area, and a spacious living area and covered parking for your convenience.\r\n\r\nThis house is for sale in Thai name."],"fave_description_th":["\u0e0b\u0e34\u0e25\u0e04\u0e4c \u0e42\u0e23\u0e49\u0e14 \u0e40\u0e1e\u0e25\u0e2a \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2b\u0e23\u0e39\u0e2b\u0e23\u0e32 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e0a\u0e31\u0e22\u0e1e\u0e24\u0e01\u0e29\u0e4c 2 \u0e43\u0e01\u0e25\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e32\u0e14\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e14\u0e08\u0e2d\u0e21\u0e40\u0e17\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e07\u0e48\u0e32\u0e22\u0e14\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e46 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e0a\u0e37\u0e48\u0e19\u0e0a\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e33\u0e23\u0e38\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e39\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e39\u0e49\u0e1e\u0e31\u0e01\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1e\u0e25\u0e34\u0e14\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e14\u0e40\u0e22\u0e35\u0e48\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e2a\u0e23\u0e30\u0e27\u0e48\u0e32\u0e22\u0e19\u0e49\u0e33\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19 \u0e2b\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e01\u0e33\u0e25\u0e31\u0e07\u0e01\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19 \u0e2a\u0e19\u0e32\u0e21\u0e40\u0e14\u0e47\u0e01\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e23\u0e37\u0e48\u0e19\u0e23\u0e21\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e2a\u0e27\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e25\u0e32\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e20\u0e39\u0e21\u0e34\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e1a\u0e19\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48 452 \u0e15\u0e23.\u0e21.(113 \u0e15\u0e23.\u0e27\u0e32)  \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 3 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e2d\u0e19 2 \u0e2b\u0e49\u0e2d\u0e07\u0e19\u0e49\u0e33 \u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19 \u0e21\u0e35\u0e2b\u0e49\u0e2d\u0e07\u0e04\u0e23\u0e31\u0e27\u0e17\u0e35\u0e48\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e43\u0e08 \u0e41\u0e25\u0e30\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e07\u0e40\u0e25\u0e48\u0e19\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e23\u0e16\u0e43\u0e19\u0e23\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\r\n\r\n\u0e1a\u0e49\u0e32\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e19\u0e35\u0e49\u0e02\u0e32\u0e22\u0e43\u0e19\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e44\u0e17\u0e22\r\n\r\n\r\n"],"fave_description_fr":["Silk Road Place, un d\u00e9veloppement r\u00e9sidentiel exquis et luxueux, est situ\u00e9 dans le soi Chaiyapruk 2, id\u00e9alement \u00e0 proximit\u00e9 des commerces et des services, tout en offrant \u00e9galement un acc\u00e8s facile aux plages de Pattaya et de Jomtien en quelques minutes en voiture. Il a acquis une r\u00e9putation louable gr\u00e2ce \u00e0 son excellent entretien et \u00e0 son haut niveau de s\u00e9curit\u00e9. De plus, les r\u00e9sidents peuvent profiter des fantastiques installations communes, qui comprennent une piscine commune rafra\u00eechissante, une salle de sport bien \u00e9quip\u00e9e, une charmante aire de jeux pour enfants et de magnifiques jardins communaux paysagers.\r\n\r\nCette maison, assise sur un terrain de 452 m2, se compose de 3 chambres, 2 salles de bains. La maison est en partie meubl\u00e9e et pr\u00e9sente une cuisine moderne, une salle \u00e0 manger accueillante, un salon spacieux et un parking couvert pour votre commodit\u00e9.\r\n\r\nCette maison est \u00e0 vendre au nom tha\u00eflandais"],"_wds_trimmed_excerpt":[""],"_wds_focus-keywords":[""],"houzez_total_property_views":["2277"],"houzez_views_by_date":["a:61:{s:10:\"05-11-2026\";i:2;s:10:\"05-12-2026\";i:6;s:10:\"05-13-2026\";i:1;s:10:\"05-14-2026\";i:5;s:10:\"05-15-2026\";i:4;s:10:\"05-16-2026\";i:2;s:10:\"05-17-2026\";i:2;s:10:\"05-18-2026\";i:2;s:10:\"05-19-2026\";i:3;s:10:\"05-21-2026\";i:3;s:10:\"05-22-2026\";i:3;s:10:\"05-23-2026\";i:2;s:10:\"05-24-2026\";i:4;s:10:\"05-25-2026\";i:4;s:10:\"05-26-2026\";i:2;s:10:\"05-27-2026\";i:2;s:10:\"05-30-2026\";i:3;s:10:\"05-31-2026\";i:2;s:10:\"06-01-2026\";i:2;s:10:\"06-02-2026\";i:2;s:10:\"06-03-2026\";i:11;s:10:\"06-04-2026\";i:4;s:10:\"06-05-2026\";i:4;s:10:\"06-06-2026\";i:2;s:10:\"06-08-2026\";i:2;s:10:\"06-09-2026\";i:1;s:10:\"06-10-2026\";i:3;s:10:\"06-11-2026\";i:2;s:10:\"06-12-2026\";i:2;s:10:\"06-13-2026\";i:1;s:10:\"06-14-2026\";i:1;s:10:\"06-15-2026\";i:3;s:10:\"06-16-2026\";i:4;s:10:\"06-17-2026\";i:2;s:10:\"06-18-2026\";i:4;s:10:\"06-19-2026\";i:2;s:10:\"06-20-2026\";i:2;s:10:\"06-21-2026\";i:8;s:10:\"06-22-2026\";i:3;s:10:\"06-23-2026\";i:3;s:10:\"06-24-2026\";i:3;s:10:\"06-25-2026\";i:6;s:10:\"06-26-2026\";i:5;s:10:\"06-27-2026\";i:3;s:10:\"06-29-2026\";i:3;s:10:\"06-30-2026\";i:2;s:10:\"07-01-2026\";i:2;s:10:\"07-02-2026\";i:3;s:10:\"07-03-2026\";i:8;s:10:\"07-04-2026\";i:1;s:10:\"07-05-2026\";i:4;s:10:\"07-06-2026\";i:1;s:10:\"07-07-2026\";i:6;s:10:\"07-08-2026\";i:2;s:10:\"07-09-2026\";i:2;s:10:\"07-10-2026\";i:2;s:10:\"07-11-2026\";i:4;s:10:\"07-12-2026\";i:2;s:10:\"07-13-2026\";i:5;s:10:\"07-14-2026\";i:3;s:10:\"07-15-2026\";i:4;}"],"houzez_recently_viewed":["2026-07-15 21:30:48"],"property_price_per_area":["32079.646017699"],"_property_price_per_area":["field_67da7c9b02034"],"fave_property_sec_price":["65000"],"_wpml_media_has_media":["1"],"fave_property_images":["1294094","1294091","1294070","1294067","1294088","1294073","1294076","1294085","1294097","1294079","1294082","1294100"],"fave_attachments":["1294106"],"customer_email":[""],"customer_mobile":[""],"customer_fax":[""],"customer_street":[""],"customer_location":[""],"customer_state":[""],"customer_postal_code":[""],"customer_country":[""],"customer_ref_remark":[""],"ref_first_name":[""],"ref_second_name":[""],"ref_email":[""],"ref_phone":[""],"ref_mobile":[""],"ref_fax":[""],"ref_street":[""],"ref_location":[""],"ref_state":[""],"ref_postal_code":[""],"ref_country":[""],"ref_remark":[""],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties\/1294066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/users\/32"}],"version-history":[{"count":0,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/properties\/1294066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/media\/1294094"}],"wp:attachment":[{"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/media?parent=1294066"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_type?post=1294066"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_status?post=1294066"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_feature?post=1294066"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_label?post=1294066"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_country?post=1294066"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_city?post=1294066"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/pattayaprestigeproperties.com\/fr\/wp-json\/wp\/v2\/property_area?post=1294066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}